{"id":1348,"date":"2025-08-08T03:01:19","date_gmt":"2025-08-08T03:01:19","guid":{"rendered":"https:\/\/demo.bravisthemes.com\/dentia\/?page_id=1348"},"modified":"2025-08-08T03:01:19","modified_gmt":"2025-08-08T03:01:19","slug":"booking","status":"publish","type":"page","link":"https:\/\/www.tarikahmet.com\/en\/booking\/","title":{"rendered":"Booking"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1348\" class=\"elementor elementor-1348\">\n\t\t\t\t<div class=\"elementor-element elementor-element-027b3bb e-flex e-con-boxed pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-parent\" data-id=\"027b3bb\" data-element_type=\"container\">\t\t\t<div class=\"e-con-inner\">\r\n\t\t<div class=\"elementor-element elementor-element-ac93b3e e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child\" data-id=\"ac93b3e\" data-element_type=\"container\"><div class=\"elementor-element elementor-element-19f759f e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child\" data-id=\"19f759f\" data-element_type=\"container\">\t\t<div class=\"elementor-element elementor-element-b665f0c elementor-widget elementor-widget-pxl_icon\" data-id=\"b665f0c\" data-element_type=\"widget\" data-widget_type=\"pxl_icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"pxl-icon-list pxl-icon1 style-default\" data-wow-delay=\"ms\">\r\n                                    <a class=\"elementor-repeater-item-d646af7\" >\r\n                    <i aria-hidden=\"true\" class=\"fas fa-envelope\"><\/i>                                    <\/a>\r\n                        <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3e9d5e elementor-widget elementor-widget-pxl_heading\" data-id=\"a3e9d5e\" data-element_type=\"widget\" data-widget_type=\"pxl_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl-pxl_heading-a3e9d5e-9201\" class=\"pxl-heading px-sub-title-default-style\">\n\t<div class=\"pxl-heading--inner\">\n\t\t\n\t\t\n\t\t<h3 class=\"pxl-item--title\" data-wow-delay=\"ms\">\n\t\t\tBook Your Appointment\t\t\n\t\t<\/h3>\n\n\t\t\t\t\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"elementor-element elementor-element-ef51d64 elementor-widget elementor-widget-pxl_text_editor\" data-id=\"ef51d64\" data-element_type=\"widget\" data-widget_type=\"pxl_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"pxl_text_editor-ef51d64-8407\" class=\"pxl-image-wg\" duration=\"1\">\n\t<div class=\"pxl-text-editor\">\n\t\t<div class=\"pxl-item--inner\" data-wow-delay=\"ms\">\n\t\t\t<p>Book your appointment today for expert dental care tailored to your needs. Healthy, beautiful smiles start with a simple step, schedule now!<\/p>\t\t\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-147ddc0 elementor-widget elementor-widget-pxl_contact_form\" data-id=\"147ddc0\" data-element_type=\"widget\" data-widget_type=\"pxl_contact_form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"pxl-contact-form pxl-contact-form1 notice-style1 box-style-none btn-w-auto\" data-wow-delay=\"ms\">\r\n        \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1382-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1382\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/1348#wpcf7-f1382-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/1348#wpcf7-f1382-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1382\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.4\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1382-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"contact2\">\n\t<div class=\"pxl-select-service\">\n\t\t<div class=\"input-filled\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"menu-258\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" multiple=\"multiple\" name=\"menu-258[]\"><option value=\"Select service\">Select service<\/option><option value=\"General Dentistry\">General Dentistry<\/option><option value=\"Cosmetic Dentistry\">Cosmetic Dentistry<\/option><option value=\"Pediatric Dentistry\">Pediatric Dentistry<\/option><option value=\"Restorative Dentistry\">Restorative Dentistry<\/option><option value=\"Preventive Dentistry\">Preventive Dentistry<\/option><option value=\"Orthodontics\">Orthodontics<\/option><\/select><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"row pxl-date-time\">\n\t\t<div class=\"col-lg-6\">\n\t\t\t<div class=\"pxl-date\">\n\t\t\t\t<div class=\"pxl-date-content\">\n\t\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-date\"><br \/>\n<i class=\"pxl--form-icon caseicon-calendar-alt\"><\/i><br \/>\n<input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required your-date\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Date\" value=\"\" type=\"text\" name=\"your-date\" \/><br \/>\n<\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"col-lg-6\">\n\t\t\t<div class=\"pxl-select-time\">\n\t\t\t\t<div class=\"input-filled\">\n\t\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"menu-259\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" multiple=\"multiple\" name=\"menu-259[]\"><option value=\"Select Time\">Select Time<\/option><option value=\"10:00\">10:00<\/option><option value=\"11:00\">11:00<\/option><option value=\"12:00\">12:00<\/option><option value=\"13:00\">13:00<\/option><option value=\"14:00\">14:00<\/option><option value=\"15:00\">15:00<\/option><option value=\"16:00\">16:00<\/option><option value=\"17:00\">17:00<\/option><option value=\"18:00\">18:00<\/option><option value=\"19:00\">19:00<\/option><option value=\"20:00\">20:00<\/option><\/select><\/span>\n\t\t\t\t\t<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"pxl-contact-mail\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-lg-4\">\n\t\t\t\t<div class=\"pxl-item-name\">\n\t\t\t\t\t<div class=\"input-filled name\">\n\t\t\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"text-707\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"text-707\" \/><\/span>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-lg-4\">\n\t\t\t\t<div class=\"pxl-item-email\">\n\t\t\t\t\t<div class=\"input-filled email\">\n\t\t\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"email-761\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"email-761\" \/><\/span>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-lg-4\">\n\t\t\t\t<div class=\"pxl-item-phone\">\n\t\t\t\t\t<div class=\"input-filled phone\">\n\t\t\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-733\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone\" value=\"\" type=\"tel\" name=\"tel-733\" \/><\/span>\n\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"pxl-item-message\">\n\t\t\t<div class=\"input-filled message\">\n\t\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"textarea-648\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Message\" name=\"textarea-648\"><\/textarea><\/span>\n\t\t\t\t<\/p>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"ct-button\">\n\t\t\t<p><button class=\"btn btn-primary\" type=\"submit\" data-animation=\"pxl-xspin\">Send Appointment<\/button>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n<\/div>\n    <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t<div class=\"elementor-element elementor-element-8315de3 e-con-full e-flex pxl-column-none pxl-row-scroll-none pxl-zoom-point-false pxl-section-overflow-visible pxl-section-fix-none pxl-full-content-with-space-none pxl-bg-color-none pxl-section-overlay-none e-con e-child\" data-id=\"8315de3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\t\t<div class=\"elementor-element elementor-element-8b7c214 elementor-widget elementor-widget-pxl_icon_box\" data-id=\"8b7c214\" data-element_type=\"widget\" data-widget_type=\"pxl_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pxl-icon-box pxl-icon-box2 style2\">\r\n\t<div class=\"pxl-item-inner\" data-wow-delay=\"ms\">\r\n                    <div class=\"pxl-item--icon\">\r\n                <i aria-hidden=\"true\" class=\"fas fa-clock\"><\/i>            <\/div>\r\n                \t\t<div class=\"pxl-meta-content\">\r\n            <h4 class=\"pxl-item-title\">\r\n                Opening Hours            <\/h4>\r\n            <span class=\"pxl-item-desc\">\r\n                Mon to Sat 08:00 - 20:00             <\/span>\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Book Your Appointment Book your appointment today for expert dental care tailored to your needs. Healthy, beautiful smiles start with a simple step, schedule now! Select serviceGeneral DentistryCosmetic DentistryPediatric DentistryRestorative DentistryPreventive DentistryOrthodontics Select Time10:0011:0012:0013:0014:0015:0016:0017:0018:0019:0020:00 Send Appointment Opening Hours Mon to Sat 08:00 &#8211; 20:00<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1348","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.tarikahmet.com\/en\/wp-json\/wp\/v2\/pages\/1348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tarikahmet.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tarikahmet.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tarikahmet.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tarikahmet.com\/en\/wp-json\/wp\/v2\/comments?post=1348"}],"version-history":[{"count":0,"href":"https:\/\/www.tarikahmet.com\/en\/wp-json\/wp\/v2\/pages\/1348\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tarikahmet.com\/en\/wp-json\/wp\/v2\/media?parent=1348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}